{"id":5165,"date":"2022-04-14T00:34:39","date_gmt":"2022-04-14T00:34:39","guid":{"rendered":"https:\/\/fiat600light.com.ar\/?p=5165"},"modified":"2022-04-14T00:34:39","modified_gmt":"2022-04-14T00:34:39","slug":"una-de-cal-y-una-de-arena-para-nestor-tortonesi","status":"publish","type":"post","link":"https:\/\/fiat600light.com.ar\/index.php\/2022\/04\/14\/una-de-cal-y-una-de-arena-para-nestor-tortonesi\/","title":{"rendered":"UNA DE CAL Y UNA DE ARENA PARA NESTOR TORTONESI"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">La vuelta de la categor\u00eda al \u00abOscar y Juan G\u00e1lvez\u00bb de Buenos Aires trajo consigo la continuidad del dominio de N\u00e9stor Tortonesi, que domino en el d\u00eda S\u00e1bado en cada salida a pista, estableciendo la pole position para el d\u00eda Domingo al cronometrar 1m45s866 a 113,503 km\/h. con el auto que atiende el Bracamonte Competici\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/04\/DSC_1983-1024x683.jpg\" alt=\"\" class=\"wp-image-5166 lazyload\" data-srcset=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/04\/DSC_1983-1024x683.jpg 1024w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/04\/DSC_1983-300x200.jpg 300w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/04\/DSC_1983-768x512.jpg 768w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/04\/DSC_1983.jpg 1500w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><\/figure>\n\n\n\n<p><strong>PRIMERA FINAL: TORTONESI GANO UNA GRAN CARRERA<\/strong><\/p>\n\n\n\n<p>La primera final fue muy disputada y termin\u00f3 con triunfo para N\u00e9stor Tortonesi. Emiliano Gonz\u00e1lez fue segundo y Facundo Di Tano complet\u00f3 el podio.La primera final en el circuito N\u00b0 8 fue atrapante, con grandes maniobras y con un repetido ganador: N\u00e9stor Tortonesi. El piloto del Bracamonte Competici\u00f3n sufri\u00f3 en las primeras vueltas de la competencia los ataques de Facundo Di Tano primero y Emiliano Gonz\u00e1lez despu\u00e9s, pero desde el 7\u00b0 giro logr\u00f3 hacer una diferencia tranquilizadora y le alcanz\u00f3 para llevarse el triunfo.Emiliano Gonz\u00e1lez en gran tarea lleg\u00f3 segundo y tras una ardua batalla Facundo Di Tano logr\u00f3 el \u00faltimo escal\u00f3n del podio.Mat\u00edas Pati\u00f1o en buena remontada, Daniel Caziani, Mat\u00edas Calvi\u00f1o y Gagliardo \u2013 Gagliardo formaron otro pelot\u00f3n que pele\u00f3 hasta el final, mientras que el top ten final lo completaron Germ\u00e1n Ciancio, Hern\u00e1n Tessone y Ezequiel Sevillano.<\/p>\n\n\n\n<p><strong>SEGUNDA FINAL: SUSPENDIDA <\/strong><\/p>\n\n\n\n<p>La segunda final se estaba desarrollando de manera normal, hasta que un muy fuerte accidente provoc\u00f3 la detenci\u00f3n de la misma con bandera roja, y la decisi\u00f3n de los pilotos de no continuar con la actividad, ante los inconvenientes f\u00edsicos que sufrieron los protagonistas, en especial N\u00e9stor Tortonesi y Hern\u00e1n Tessone, qui\u00e9nes debieron ser trasladados al Sanatorio G\u00fcemes para su inmediata atenci\u00f3n.<br>Adan Gagliardo, el otro involucrado, no sufri\u00f3 heridas de consideraci\u00f3n por suerte. <br>Ambos volantes se encuentran en franca recuperaci\u00f3n.  <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vuelta de la categor\u00eda al \u00abOscar y Juan G\u00e1lvez\u00bb de Buenos Aires trajo consigo la continuidad del dominio de N\u00e9stor Tortonesi, que domino en el d\u00eda S\u00e1bado en cada [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5167,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-5165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5165"}],"version-history":[{"count":1,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5165\/revisions"}],"predecessor-version":[{"id":5168,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/5165\/revisions\/5168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/media\/5167"}],"wp:attachment":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}