{"id":6440,"date":"2022-10-19T23:25:43","date_gmt":"2022-10-19T23:25:43","guid":{"rendered":"https:\/\/fiat600light.com.ar\/?p=6440"},"modified":"2022-10-19T23:25:43","modified_gmt":"2022-10-19T23:25:43","slug":"dobletazo-de-calvino-en-el-mouras","status":"publish","type":"post","link":"https:\/\/fiat600light.com.ar\/index.php\/2022\/10\/19\/dobletazo-de-calvino-en-el-mouras\/","title":{"rendered":"DOBLETAZO DE CALVI\u00d1O EN EL MOURAS !"},"content":{"rendered":"\n<p>Una nueva fecha del torneo 2022 paso para los Fiat 600 Light, en este caso en el Mouras de La Plata, y dej\u00f3 un gran dominio de Mat\u00edas Calvi\u00f1o, qui\u00e9n se alz\u00f3 con la victoria en las dos finales. <\/p>\n\n\n\n<p>Esto es lo que sucedi\u00f3&#8230;<\/p>\n\n\n\n<p>BAUTISMO DE \u201cPOLE\u201d<\/p>\n\n\n\n<p>Emiliano Gonz\u00e1lez consigui\u00f3 su primera \u201cpole positi\u00f3n\u201d de la temporada, en una clasificaci\u00f3n por dem\u00e1s ajustada donde super\u00f3 a Mat\u00edas Calvi\u00f1o por escasas 63 mil\u00e9simas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-src=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0302-1024x682.jpg\" alt=\"\" class=\"wp-image-6442 lazyload\" data-srcset=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0302-1024x682.jpg 1024w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0302-300x200.jpg 300w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0302-768x512.jpg 768w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0302.jpg 1280w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/682;\" \/><\/figure>\n\n\n\n<p>Cerrando la tarde platense se disput\u00f3 la clasificaci\u00f3n y la misma result\u00f3 muy ajustada, con una intensa y disputada lucha donde vuelta a vuelta, Emiliano Gonz\u00e1lez y Mat\u00edas Calvi\u00f1o mejoraban el registro, para finalmente ser el piloto de Luis Guill\u00f3n el m\u00e1s r\u00e1pido, qued\u00e1ndose con un tiempo de 1m24s870 a 123,012 km\/h, en el trazado corto. Calvi\u00f1o fue segundo y Mat\u00edas Pati\u00f1o, en el \u00faltimo intento, se posicion\u00f3 3\u00b0 a 3 d\u00e9cimas. Daniel Caziani 4\u00b0 a medio segundo y el quinteto de punta lo complet\u00f3 Jonathan Rinc\u00f3n.<\/p>\n\n\n\n<p>Mauro Risoli fue 6\u00b0, Ezequiel Sevillano 7\u00b0, Gonzalo Tamagno, Emiliano Polito y Enzo Nieto, que result\u00f3 el m\u00e1s r\u00e1pido del primer grupo clasificatorio que sali\u00f3 a pista, cerr\u00f3 el top ten inicial.<\/p>\n\n\n\n<p>UNA VICTORIA SUFRIDA<\/p>\n\n\n\n<p>Mat\u00edas Calvi\u00f1o debi\u00f3 trabajar y mucho para llevarse el triunfo, en la primera final de los Fiat 600 Light 1.3i. Daniel Caziani fue segundo y Mat\u00edas Pati\u00f1o complet\u00f3 el podio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-src=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0116-1024x682.jpg\" alt=\"\" class=\"wp-image-6443 lazyload\" data-srcset=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0116-1024x682.jpg 1024w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0116-300x200.jpg 300w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0116-768x512.jpg 768w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0116.jpg 1280w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/682;\" \/><\/figure>\n\n\n\n<p>En una ma\u00f1ana soleada en La Plata, se le dio continuidad al 8\u00b0 cap\u00edtulo con la primera final que result\u00f3 muy disputada hasta la ca\u00edda de la bandera a cuadros.<\/p>\n\n\n\n<p>En el inicio fue el \u201cpoleman\u201d, Emiliano Gonz\u00e1lez, quien comando, seguido de cerca por Calvi\u00f1o que no le daba respiro. Mat\u00edas Pati\u00f1o era tercero, pero en el 4\u00b0 giro fue Daniel Caziani quien lograba superar al campe\u00f3n. Atr\u00e1s, hab\u00eda varias luchas, que tampoco le quitaban ritmo a una competencia que vuelta a vuelta mostraba entretenidas y disputadas peleas por todos los puestos.<\/p>\n\n\n\n<p>El gran golpe de escena ocurri\u00f3 en el 9\u00b0 giro, cuando a la salida de la 1, el l\u00edder realiz\u00f3 un semi trompo que lo releg\u00f3 y le permiti\u00f3 a Calvi\u00f1o tomar la delantera, para de all\u00ed en mas encaminarse a su 8\u00aa victoria del a\u00f1o y estirar la diferencia en el campeonato.<\/p>\n\n\n\n<p>Daniel Caziani logr\u00f3 terminar segundo y se mantiene firme en la lucha por la corona, en tanto que Mat\u00edas Pati\u00f1o culmin\u00f3 3\u00b0 y sum\u00f3 un nuevo podio, para seguir alimentando sus chances de dar batalla hasta el final.<\/p>\n\n\n\n<p>En otra buena actuaci\u00f3n Mauro Risoli finaliz\u00f3 4\u00b0, por delante de Emiliano Gonz\u00e1lez, Gonzalo Tamagno, Emiliano Polito que mantuvo una interesante lucha con Ezequiel Sevillano, Mat\u00edas Gorosito y Jos\u00e9 Morelli cerrando el top ten final.<\/p>\n\n\n\n<p>CALVI\u00d1O Y OTRA GRAN VICTORIA<\/p>\n\n\n\n<p>Mat\u00edas Calvi\u00f1o cerr\u00f3 un fin de semana perfecto y alcanz\u00f3 un nuevo triunfo, que le permite tomar distancias en la cima del campeonato. Daniel Caziani fue el escolta nuevamente y Emiliano Polito, en gran final, complet\u00f3 el podio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" data-src=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0245-1024x682.jpg\" alt=\"\" class=\"wp-image-6444 lazyload\" data-srcset=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0245-1024x682.jpg 1024w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0245-300x200.jpg 300w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0245-768x512.jpg 768w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2022\/10\/DSC_0245.jpg 1280w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/682;\" \/><\/figure>\n\n\n\n<p>Cerrando la 8\u00aa final del a\u00f1o, los Fiat 600 Light 1.3i volvieron a brindar un extraordinario espect\u00e1culo, con grandes maniobras de superaci\u00f3n y una lucha por la delantera que se mantuvo hasta la ca\u00edda de la bandera a cuadros.<\/p>\n\n\n\n<p>Mat\u00edas Calvi\u00f1o y Daniel Caziani intercambiaron posiciones en varias oportunidades, con muy lindas maniobras, para finalmente en el 9\u00b0 giro el l\u00edder del campeonato tomar la delantera y de all\u00ed en m\u00e1s se encamin\u00f3 a un gran triunfo, el 9\u00b0 del a\u00f1o que le permite volver a estirar distancias en la tabla anual.<\/p>\n\n\n\n<p>Daniel Caziani finaliz\u00f3 segundo, en otro gran fin de semana para el piloto de Lan\u00fas, mientras que, en gran remontada, Emiliano Polito ocup\u00f3 el \u00faltimo escal\u00f3n del podio.<\/p>\n\n\n\n<p>Gonzalo Tamagno nuevamente redonde\u00f3 un gran trabajo llegando 4\u00b0, por delante de Ezequiel Sevillano. Jos\u00e9 Morelli fue otro de los que avanz\u00f3 y termin\u00f3 6\u00b0, Jonathan Rinc\u00f3n que se vino de atr\u00e1s fue 7\u00b0, Mat\u00edas Gorosito 8\u00b0, Gustavo Valiante 9\u00b0 y Juan Cruz Bueno complet\u00f3 el top ten final.<\/p>\n\n\n\n<p>Tras dos grandes finales, el campeonato entr\u00f3 en su recta final y a Dolores, escenario del pr\u00f3ximo episodio, llegan Calvi\u00f1o con 226 puntos, mientras que Caziani se ubica segundo con 216,5.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nueva fecha del torneo 2022 paso para los Fiat 600 Light, en este caso en el Mouras de La Plata, y dej\u00f3 un gran dominio de Mat\u00edas Calvi\u00f1o, qui\u00e9n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-6440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=6440"}],"version-history":[{"count":1,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6440\/revisions"}],"predecessor-version":[{"id":6445,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/6440\/revisions\/6445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/media\/6441"}],"wp:attachment":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=6440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=6440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=6440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}