{"id":7200,"date":"2023-04-21T23:30:36","date_gmt":"2023-04-21T23:30:36","guid":{"rendered":"https:\/\/fiat600light.com.ar\/?p=7200"},"modified":"2023-04-21T23:30:39","modified_gmt":"2023-04-21T23:30:39","slug":"7200","status":"publish","type":"post","link":"https:\/\/fiat600light.com.ar\/index.php\/2023\/04\/21\/7200\/","title":{"rendered":""},"content":{"rendered":"\n<h1 class=\"wp-block-heading has-small-font-size\">Diego Haramburu y Flor Silva cumplieron el sue\u00f1o y pudieron poner en pista su auto.<br>Luego de varios a\u00f1os de trabajos pudieron poner en pista la nueva unidad y de la cual Diego fue el encargado de manejar en ambas finales.<br><br><img decoding=\"async\" width=\"1200\" height=\"800\" class=\"wp-image-7194 lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/800;width: 1200px;\" data-src=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/04\/DSC_0227.jpg\" alt=\"\" data-srcset=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/04\/DSC_0227.jpg 1280w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/04\/DSC_0227-300x200.jpg 300w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/04\/DSC_0227-1024x682.jpg 1024w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/04\/DSC_0227-768x512.jpg 768w\" data-sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>\u201cEn esta primera fecha pusimos el auto nuevo en pista y tuvimos algunos inconvenientes con la pedalera que nos dificult\u00f3 un poco el manejo a la hora de frenar, pero m\u00e1s all\u00e1 de eso funcion\u00f3 de forma correcta y estamos en proceso de aprendizaje y adaptaci\u00f3n\u201d comenz\u00f3 diciendo Diego que ya apunta a Dolores, donde correr\u00e1n una final cada uno con Flor.<br>\u201cPara la pr\u00f3xima fecha esperamos poder girar dentro de los tiempos razonables y terminar lo m\u00e1s adelante posible. Dolores es un circuito que por la \u00fanica experiencia que tuve me gust\u00f3, hay que manejar bastante y eso es lo que vamos a tratar de hacer. En el auto se realiz\u00f3 un repaso general y se modific\u00f3 la pedalera. Agradezco a todo el EMG por el trabajo que hacen y la buena predisposici\u00f3n en todo momento\u201d cerr\u00f3.<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Diego Haramburu y Flor Silva cumplieron el sue\u00f1o y pudieron poner en pista su auto.Luego de varios a\u00f1os de trabajos pudieron poner en pista la nueva unidad y de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-7200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=7200"}],"version-history":[{"count":1,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7200\/revisions"}],"predecessor-version":[{"id":7201,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7200\/revisions\/7201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/media\/7188"}],"wp:attachment":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=7200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=7200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=7200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}