{"id":7974,"date":"2023-06-30T14:59:14","date_gmt":"2023-06-30T14:59:14","guid":{"rendered":"https:\/\/fiat600light.com.ar\/?p=7974"},"modified":"2023-06-30T14:59:15","modified_gmt":"2023-06-30T14:59:15","slug":"objetivo-descontar","status":"publish","type":"post","link":"https:\/\/fiat600light.com.ar\/index.php\/2023\/06\/30\/objetivo-descontar\/","title":{"rendered":"OBJETIVO: DESCONTAR"},"content":{"rendered":"\n<p>Mat\u00edas Balladares quiere volver a pelear bien arriba en los Fiat 600 Light 1.3i y el objetivo ser\u00e1 descontar puntos en la tabla anual.<\/p>\n\n\n\n<p>Tras su estupendo debut en Dolores con victoria, la \u00faltima fecha dejo sensaciones encontradas para el piloto de Lan\u00fas, ya que en la primera final redonde\u00f3 un buen resultado, pero un choque lo dej\u00f3 con las manos vac\u00edas en la 2\u00aa. Su pap\u00e1, el \u2018Tala\u2019, ya est\u00e1 trabajando en el auto para llegar de la mejor manera a la 5\u00aa cita del a\u00f1o.<\/p>\n\n\n\n<p><img decoding=\"async\" width=\"1200\" height=\"800\" class=\"wp-image-7957 lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/800;width: 1200px;\" data-src=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/06\/DSC1998.jpg\" alt=\"\" data-srcset=\"https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/06\/DSC1998.jpg 1280w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/06\/DSC1998-300x200.jpg 300w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/06\/DSC1998-1024x682.jpg 1024w, https:\/\/fiat600light.com.ar\/wp-content\/uploads\/2023\/06\/DSC1998-768x512.jpg 768w\" data-sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/><br><a href=\"https:\/\/www.instagram.com\/maty_balladares\/\">@maty_balladares<\/a><br>\u201cEsperamos la fecha en La Plata con ganas y con la confianza de que vamos a seguir mejorando. Esta \u00faltima carrera no fue del todo positiva por m\u00e1s que el auto funcion\u00f3 perfecto y en la 2\u00aa final pudimos seguir el ritmo de la punta, pero el choque hizo que no termine de ser bueno el fin de semana\u201d comenz\u00f3 diciendo \u2018Matu\u2019 que a\u00f1adi\u00f3: \u201cAhora se est\u00e1 trabajando en reparar el auto y en la parte de los frenos para tratar de mejorar ya que el motor funciona muy bien, por lo que vamos al circuito largo a buscar la mayor cantidad de puntos para no quedar lejos en el campeonato\u201d coment\u00f3 quien se ubica 9\u00b0 en la tabla anual con 54 unidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mat\u00edas Balladares quiere volver a pelear bien arriba en los Fiat 600 Light 1.3i y el objetivo ser\u00e1 descontar puntos en la tabla anual. Tras su estupendo debut en Dolores [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-7974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=7974"}],"version-history":[{"count":1,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7974\/revisions"}],"predecessor-version":[{"id":7975,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/7974\/revisions\/7975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/media\/7948"}],"wp:attachment":[{"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=7974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=7974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fiat600light.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=7974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}